{"id":11024,"date":"2020-01-29T11:03:44","date_gmt":"2020-01-29T14:03:44","guid":{"rendered":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/?p=11024"},"modified":"2020-01-31T11:07:02","modified_gmt":"2020-01-31T14:07:02","slug":"disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales","status":"publish","type":"post","link":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/pb\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/","title":{"rendered":"Disponen de colectivos gratuitos para los carnavales oficiales"},"content":{"rendered":"<p class=\"copete\">La Municipalidad de Corrientes dio a conocer c\u00f3mo ser\u00e1 el sistema de transporte urbano de pasajeros <strong>sin costo<\/strong> hacia y desde el Cors\u00f3dromo Nolo Al\u00edas, para que los vecinos puedan disfrutar de la Fiesta de Momo. Desde las 20 horas se podr\u00e1n abordar las unidades identificadas debidamente, que tendr\u00e1n una frecuencia de entre 15 y 25 minutos. Conoc\u00e9 el recorrido de cada l\u00ednea en la siguiente nota. \u00a0<\/p>\n<div class=\"acciones\"><span style=\"font-size: 1rem;\">En un esfuerzo realizado por la Municipalidad de Corrientes con el objetivo de brindar un servicio gratuito a los vecinos de la ciudad, a partir de este viernes \u2013inicio de los carnavales oficiales- se brindar\u00e1 traslado sin costo alguno hacia el cors\u00f3dromo Nolo Al\u00edas a trav\u00e9s del transporte p\u00fablico.<\/span><\/div>\n<div class=\"cuerpo\">\n<p>El servicio ser\u00e1 a demanda y comenzar\u00e1 a funcionar a partir de las 20; cuyas unidades estar\u00e1n disponibles en cada cabecera de l\u00ednea para partir hacia el cors\u00f3dromo Nolo Al\u00edas. Una vez finalizado el corso, transportar\u00e1n a los pasajeros realizando el recorrido inverso.<\/p>\n<p><strong><em>\u201cEste es un gran esfuerzo que realiza el municipio a la hora de poner al vecino en contacto con este gran evento como son los carnavales y en el marco de un compromiso junto a las empresas de cada uno de los ramales existentes, de disponer una unidad por ramal abocada al traslado gratuito hacia el cors\u00f3dromo\u201d, enfatiz\u00f3 el secretario de Movilidad Urbana y Seguridad Ciudadana, Jorge Sladek.<\/em><\/strong><\/p>\n<div id=\"embeds\" class=\"inser center-block\">\n<div class=\"SandboxRoot env-bp-350\" data-twitter-event-id=\"0\">\n<div id=\"twitter-widget-0\" class=\"EmbeddedTweet EmbeddedTweet--cta js-clickToOpenTarget\" lang=\"es\" data-click-to-open-target=\"https:\/\/twitter.com\/municorrientes\/status\/1222514494779330568\" data-iframe-title=\"Tweet de Twitter\" data-scribe=\"page:tweet\" data-twitter-event-id=\"1\">\n<div class=\"EmbeddedTweet-tweetContainer\">\n<div class=\"EmbeddedTweet-tweet\">\n<blockquote class=\"Tweet h-entry js-tweetIdInfo subject expanded\" cite=\"https:\/\/twitter.com\/municorrientes\/status\/1222514494779330568\" data-tweet-id=\"1222514494779330568\" data-scribe=\"section:subject\">\n<div class=\"Tweet-header\">\n<div class=\"Tweet-brand\">\n<div title=\"Ver en Twitter\" role=\"presentation\" aria-label=\"Ver en Twitter\">\u00a0<\/div>\n<div class=\"Icon Icon--twitter \" title=\"Ver en Twitter\" role=\"presentation\" aria-label=\"Ver en Twitter\"><span style=\"font-size: 1rem;\">Conoc\u00e9 los recorridos de ida y vuelta al corsodromo ac\u00e1\u00a0<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"Tweet-body e-entry-content\" data-scribe=\"component:tweet\">\n<div class=\"Tweet-card\">\n<article class=\"MediaCard\n           \n           customisable-border\" dir=\"ltr\" data-scribe=\"component:card\"><\/p>\n<div class=\"MediaCard-mediaContainer MediaCard--roundedTop MediaCard--roundedBottom js-cspForcedStyle\" data-scribe=\"element:photo_grid\" data-style=\"padding-bottom: 50%\">\n<div class=\"MediaCard-mediaAsset ImageGrid ImageGrid--4\">\u00a0<\/div>\n<\/div>\n<\/article>\n<\/div>\n<div class=\"TweetInfo\">\n<div class=\"tweet-InformationCircle\" data-scribe=\"element:notice\"><span style=\"font-size: 1rem;\">La frecuencia de cada una de las unidades ser\u00e1 de entre 15 a 25 minutos, seg\u00fan la demanda, como as\u00ed tambi\u00e9n los colectivos estar\u00e1n identificados con la leyenda\u00a0 \u201cAl Corso\u201d. Adem\u00e1s, durante el recorrido cualquier vecino puede esperar en diferentes paradas para hacer uso de este servicio.<\/span><\/div>\n<\/div>\n<\/div>\n<\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>RECORRIDOS<\/p>\n<p><strong>IDA AL CORS\u00d3DROMO (DESDE LAS 20 EN CADA CABECERA)<\/strong><\/p>\n<p><a class=\"fotos-desarrollo unlink\" title=\"Disponen de colectivos gratuitos para los carnavales oficiales\" href=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2020-01-29\/171555.jpg\"><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2020-01-29\/171555.jpg\" \/><\/a><a class=\"fotos-desarrollo unlink\" title=\"Disponen de colectivos gratuitos para los carnavales oficiales\" href=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2020-01-29\/363352.jpg\"><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2020-01-29\/363352.jpg\" \/><\/a><\/p>\n<p><strong>101 B\/C B\u00baPonce\/Cremonte\/San Ger\u00f3nimo<\/strong><\/p>\n<p>Por B\u00ba Ponce &#8211; Ruta 5 &#8211; B\u00ba Cremonte- Avenida Centenario &#8211; avenida Laprida &#8211; B\u00ba San Ger\u00f3nimo &#8211; avenida Libertad &#8211; Mari\u00f1o &#8211; avenida R\u00edo Chico &#8211; Ruta 12<\/p>\n<p>&nbsp;<\/p>\n<p><strong>110 A B\u00baMolina Punta\/Cementerio<\/strong><\/p>\n<p>Por avenida Libertad &#8211; Las Violetas &#8211; R\u00edo Chico &#8211; Ruta 12<\/p>\n<p>&nbsp;<\/p>\n<p><strong>110 C-Santa Catalina<\/strong><\/p>\n<p>350 Viviendas-Santa Catalina- Av. Maip\u00fa-Ruta 12-Cors\u00f3dromo<\/p>\n<p>&nbsp;<\/p>\n<p><strong>103 &#8211; B\u00ba Dr. Monta\u00f1a<\/strong><\/p>\n<p>Por avenida Maip\u00fa &#8211; Avenida Ferr\u00e9 &#8211; Avenida Artigas &#8211; Ayacucho &#8211; Walmart &#8211; Avenida Armenia &#8211; Zona Apip\u00e9 &#8211; Ruta 12<\/p>\n<p>&nbsp;<\/p>\n<p><strong>104 A Puente \/ B\u00ba Juan de Vera<\/strong><\/p>\n<p>Por Alberdi &#8211; Garay &#8211; Col\u00f3n &#8211; Guastavino &#8211; avenida 3 de Abril &#8211; avenida Chacabuco &#8211; avenida Armenia &#8211; Zona Apip\u00e9 &#8211; Ruta 12<\/p>\n<p>&nbsp;<\/p>\n<p><strong>104 C &#8211; B\u00ba Alta Gracia<\/strong><\/p>\n<p>Por Alta Gracia &#8211; Paysand\u00fa &#8211; Rafaela &#8211; avenida del IV Centenario &#8211; Mendoza &#8211; avenida 3 de Abril &#8211; avenida Chacabuco &#8211; Centenario &#8211; avenida Laprida &#8211; Zona Apip\u00e9 &#8211; Ruta 12<\/p>\n<p>&nbsp;<\/p>\n<p><strong>104 D &#8211; B\u00ba 1000 Viviendas\/Centro<\/strong><\/p>\n<p>Por Cosqu\u00edn- Avenida Sarmiento &#8211; Espa\u00f1a &#8211; B\u00ba Ba\u00f1ado Norte &#8211; Avenida Armenia &#8211; Zona Apip\u00e9 &#8211; Ruta 12<\/p>\n<p>&nbsp;<\/p>\n<p><strong>105 A\/B &#8211; Puerto\/Centro<\/strong><\/p>\n<p>Por Salta &#8211; Hip\u00f3lito Yrigoyen &#8211; avenida Chacabuco &#8211; avenida Armenia &#8211; B\u00ba Docente &#8211; B\u00ba Molina Punta &#8211; Ruta 12<\/p>\n<p>&nbsp;<\/p>\n<p><strong>106 A\/B &#8211; B\u00ba 500 Viviendas\/ Pirayu\u00ed\/ B\u00ba Nuevo<\/strong><\/p>\n<p>Sale de las 500 Viviendas &#8211; Cuba &#8211; B\u00ba Nuevo &#8211; San Francisco &#8211; Montecarlo &#8211; Avenida Cazadores Correntinos &#8211; Ruta 12 &#8211; Avenida Laprida &#8211; Zona Apip\u00e9 &#8211; Ruta 12<\/p>\n<p>&nbsp;<\/p>\n<p><strong>108 A\/B &#8211; B\u00ba Quintana \/ Laguna Seca<\/strong><\/p>\n<p>Por Cangallo &#8211; Medrano- Laguna Seca- Avenida Cazadores Correntinos &#8211; avenida Chacabuco &#8211; Avenida Independencia &#8211; Ruta 12 &#8211; Avenida Laprida &#8211; Campus &#8211; Ruta 12<\/p>\n<p>&nbsp;<\/p>\n<p>VUELTA DEL CORS\u00d3DROMO<\/p>\n<p><a class=\"fotos-desarrollo unlink\" title=\"Disponen de colectivos gratuitos para los carnavales oficiales\" href=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2020-01-29\/567403.jpg\"><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2020-01-29\/567403.jpg\" \/><\/a><a class=\"fotos-desarrollo unlink\" title=\"Disponen de colectivos gratuitos para los carnavales oficiales\" href=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2020-01-29\/850916.jpg\"><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2020-01-29\/850916.jpg\" \/><\/a><\/p>\n<p><strong>103 B\u00ba &#8211; Dr. Monta\u00f1a<\/strong><\/p>\n<p>Campus &#8211; San Ger\u00f3nimo &#8211; Centenario &#8211; Chacabuco &#8211; Ferr\u00e9 &#8211; Maip\u00fa &#8211; Dr. Monta\u00f1a<\/p>\n<p>&nbsp;<\/p>\n<p><strong>104 A &#8211; Puente \/ B\u00ba Juan de Vera<\/strong><\/p>\n<p>Campus &#8211; Armenia &#8211; Centro &#8211; Cementerio &#8211; Cosqu\u00edn &#8211; Alta Gracia<\/p>\n<p>&nbsp;<\/p>\n<p><strong>104 C &#8211; B\u00ba Alta Gracia<\/strong><\/p>\n<p>Campus &#8211; Armenia &#8211; Poncho Verde &#8211; Puerto &#8211; Hospital Vidal &#8211; 215 Viviendas<\/p>\n<p>&nbsp;<\/p>\n<p><strong>105 A\/B Puerto\/Centro<\/strong><\/p>\n<p>Molina Punta &#8211; Docente &#8211; Shopping &#8211; San Mart\u00edn &#8211; Centro &#8211; Gutenberg &#8211; 1000 Viviendas<\/p>\n<p>&nbsp;<\/p>\n<p><strong>106 A\/B\/C B\u00ba 500 Viviendas\/ Pirayu\u00ed\/ B\u00ba Nuevo<\/strong><\/p>\n<p>Ruta 12 &#8211; Rotonda &#8211; 17 de Agosto &#8211; B\u00ba Nuevo &#8211; Pirayu\u00ed &#8211; 500 Viviendas<\/p>\n<p>&nbsp;<\/p>\n<p><strong>108 A\/B &#8211; B\u00ba Quintana \/ Laguna Seca<\/strong><\/p>\n<p>Ruta 12 &#8211; Independencia &#8211; Chacabuco &#8211; Cazadores Correntinos &#8211; Laguna Seca \u2013 Quintana<\/p>\n<p>&nbsp;<\/p>\n<p><strong>101 B\/C &#8211; B\u00ba Ponce\/ Cremonte\/ San Ger\u00f3nimo<\/strong><\/p>\n<p>Ruta 12 &#8211; Avenida R\u00edo Chico &#8211; Calle Mari\u00f1o &#8211; Avenida Libertad &#8211; B\u00ba San Ger\u00f3nimo &#8211; Avenida Laprida &#8211; Avenida Centenario &#8211; B\u00ba Cremonte &#8211; Ruta 5 &#8211; Cabecera del B\u00ba Ponce<\/p>\n<p><strong>\u00a0110 A &#8211; B\u00ba Molina Punta &#8211; Cementerio<\/strong><\/p>\n<p>Cors\u00f3dromo &#8211; Ruta 12 &#8211; Avenida R\u00edo Chico &#8211; Las Violetas &#8211; Avenida Libertad<\/p>\n<p><strong>\u00a0110 C-Santa Catalina<\/strong><\/p>\n<p>Cors\u00f3dromo &#8211; Ruta 12 &#8211; Av. Maip\u00fa- Santa Catalina- 350 Viviendas \u00a0\u00a0<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Municipalidad de Corrientes dio a conocer c\u00f3mo ser\u00e1 el sistema de transporte urbano de pasajeros sin costo hacia y desde el Cors\u00f3dromo Nolo Al\u00edas, para que los vecinos puedan disfrutar de la Fiesta de Momo. Desde las 20 horas se podr\u00e1n abordar las unidades identificadas debidamente, que tendr\u00e1n una frecuencia de entre 15 y<a href=\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/pb\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/\" class=\"ver-mas\">Ver Mais &rarr;<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-11024","post","type-post","status-publish","format-standard","hentry","category-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Disponen de colectivos gratuitos para los carnavales oficiales - Ciudad de Corrientes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Disponen de colectivos gratuitos para los carnavales oficiales - Ciudad de Corrientes\" \/>\n<meta property=\"og:description\" content=\"La Municipalidad de Corrientes dio a conocer c\u00f3mo ser\u00e1 el sistema de transporte urbano de pasajeros sin costo hacia y desde el Cors\u00f3dromo Nolo Al\u00edas, para que los vecinos puedan disfrutar de la Fiesta de Momo. Desde las 20 horas se podr\u00e1n abordar las unidades identificadas debidamente, que tendr\u00e1n una frecuencia de entre 15 yVer Mais &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/\" \/>\n<meta property=\"og:site_name\" content=\"Ciudad de Corrientes\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-29T14:03:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-31T14:07:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2020-01-29\/171555.jpg\" \/>\n<meta name=\"author\" content=\"Eduardo Larosa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eduardo Larosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/\"},\"author\":{\"name\":\"Eduardo Larosa\",\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/#\/schema\/person\/4b05030f42772fc0820234c0d568f9de\"},\"headline\":\"Disponen de colectivos gratuitos para los carnavales oficiales\",\"datePublished\":\"2020-01-29T14:03:44+00:00\",\"dateModified\":\"2020-01-31T14:07:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/\"},\"wordCount\":811,\"publisher\":{\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/#organization\"},\"image\":{\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2020-01-29\/171555.jpg\",\"articleSection\":[\"Imprensa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/\",\"url\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/\",\"name\":\"Disponen de colectivos gratuitos para los carnavales oficiales - Ciudad de Corrientes\",\"isPartOf\":{\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2020-01-29\/171555.jpg\",\"datePublished\":\"2020-01-29T14:03:44+00:00\",\"dateModified\":\"2020-01-31T14:07:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/#primaryimage\",\"url\":\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2020-01-29\/171555.jpg\",\"contentUrl\":\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2020-01-29\/171555.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Disponen de colectivos gratuitos para los carnavales oficiales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/#website\",\"url\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/\",\"name\":\"Ciudad de Corrientes\",\"description\":\"Secretaria de Turismo, Deporte y Cultural\",\"publisher\":{\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/#organization\",\"name\":\"Secretaria de Turismo, Deporte y Cultura\",\"url\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/visitcorrientes.tur.ar\/wp-content\/uploads\/2018\/07\/iso.png\",\"contentUrl\":\"https:\/\/visitcorrientes.tur.ar\/wp-content\/uploads\/2018\/07\/iso.png\",\"width\":547,\"height\":178,\"caption\":\"Secretaria de Turismo, Deporte y Cultura\"},\"image\":{\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/#\/schema\/person\/4b05030f42772fc0820234c0d568f9de\",\"name\":\"Eduardo Larosa\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Disponen de colectivos gratuitos para los carnavales oficiales - Ciudad de Corrientes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/","og_locale":"pt_BR","og_type":"article","og_title":"Disponen de colectivos gratuitos para los carnavales oficiales - Ciudad de Corrientes","og_description":"La Municipalidad de Corrientes dio a conocer c\u00f3mo ser\u00e1 el sistema de transporte urbano de pasajeros sin costo hacia y desde el Cors\u00f3dromo Nolo Al\u00edas, para que los vecinos puedan disfrutar de la Fiesta de Momo. Desde las 20 horas se podr\u00e1n abordar las unidades identificadas debidamente, que tendr\u00e1n una frecuencia de entre 15 yVer Mais &rarr;","og_url":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/","og_site_name":"Ciudad de Corrientes","article_published_time":"2020-01-29T14:03:44+00:00","article_modified_time":"2020-01-31T14:07:02+00:00","og_image":[{"url":"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2020-01-29\/171555.jpg"}],"author":"Eduardo Larosa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Eduardo Larosa","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/#article","isPartOf":{"@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/"},"author":{"name":"Eduardo Larosa","@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/#\/schema\/person\/4b05030f42772fc0820234c0d568f9de"},"headline":"Disponen de colectivos gratuitos para los carnavales oficiales","datePublished":"2020-01-29T14:03:44+00:00","dateModified":"2020-01-31T14:07:02+00:00","mainEntityOfPage":{"@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/"},"wordCount":811,"publisher":{"@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/#organization"},"image":{"@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2020-01-29\/171555.jpg","articleSection":["Imprensa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/","url":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/","name":"Disponen de colectivos gratuitos para los carnavales oficiales - Ciudad de Corrientes","isPartOf":{"@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/#primaryimage"},"image":{"@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2020-01-29\/171555.jpg","datePublished":"2020-01-29T14:03:44+00:00","dateModified":"2020-01-31T14:07:02+00:00","breadcrumb":{"@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/#primaryimage","url":"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2020-01-29\/171555.jpg","contentUrl":"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2020-01-29\/171555.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/disponen-de-colectivos-gratuitos-para-los-carnavales-oficiales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/"},{"@type":"ListItem","position":2,"name":"Disponen de colectivos gratuitos para los carnavales oficiales"}]},{"@type":"WebSite","@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/#website","url":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/","name":"Ciudad de Corrientes","description":"Secretaria de Turismo, Deporte y Cultural","publisher":{"@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/#organization","name":"Secretaria de Turismo, Deporte y Cultura","url":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/#\/schema\/logo\/image\/","url":"https:\/\/visitcorrientes.tur.ar\/wp-content\/uploads\/2018\/07\/iso.png","contentUrl":"https:\/\/visitcorrientes.tur.ar\/wp-content\/uploads\/2018\/07\/iso.png","width":547,"height":178,"caption":"Secretaria de Turismo, Deporte y Cultura"},"image":{"@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/#\/schema\/person\/4b05030f42772fc0820234c0d568f9de","name":"Eduardo Larosa"}]}},"_links":{"self":[{"href":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/pb\/wp-json\/wp\/v2\/posts\/11024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/pb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/pb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/pb\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/pb\/wp-json\/wp\/v2\/comments?post=11024"}],"version-history":[{"count":6,"href":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/pb\/wp-json\/wp\/v2\/posts\/11024\/revisions"}],"predecessor-version":[{"id":11113,"href":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/pb\/wp-json\/wp\/v2\/posts\/11024\/revisions\/11113"}],"wp:attachment":[{"href":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/pb\/wp-json\/wp\/v2\/media?parent=11024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/pb\/wp-json\/wp\/v2\/categories?post=11024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desarrollovisit.ciudaddecorrientes.gov.ar\/pb\/wp-json\/wp\/v2\/tags?post=11024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}